{"id":816,"date":"2018-04-13T12:14:19","date_gmt":"2018-04-13T12:14:19","guid":{"rendered":"http:\/\/estacioserveimaset.com\/es\/?p=816"},"modified":"2018-04-13T12:14:19","modified_gmt":"2018-04-13T12:14:19","slug":"motor-gasolina-diesel","status":"publish","type":"post","link":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/","title":{"rendered":"\u00bfEn qu\u00e9 se diferencia un motor de gasolina de uno di\u00e9sel?"},"content":{"rendered":"<p>Motor de gasolina, motor di\u00e9sel, tal vez sea una cuesti\u00f3n que parezca algo pasado de moda o fuera de contexto. Sin embargo, son los tipos de motor que m\u00e1s se utilizan en la actualidad y cada uno tiene sus propias caracter\u00edsticas que lo diferencian del otro. A continuaci\u00f3n, daremos un repaso sobre \u00e9stas caracter\u00edsticas relevantes que marcan sus diferencias.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contingut<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a0496ac62117\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a0496ac62117\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/#Motor_de_gasolina\" >Motor de gasolina<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/#Motor_diesel\" >Motor diesel<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/#Diferencias_entre_un_motor_diesel_y_uno_de_gasolina\" >Diferencias entre un motor diesel y uno de gasolina<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Motor_de_gasolina\"><\/span>Motor de gasolina<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Un motor a gasolina, conocido tambi\u00e9n como motor de explosi\u00f3n, funciona con combusti\u00f3n interna. La combusti\u00f3n interna transforma la energ\u00eda qu\u00edmica de un carburante, en este caso gasolina, en energ\u00eda mec\u00e1nica. La explosi\u00f3n del combustible hace que los gases que contienen se expandan provocando el movimiento del pist\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Motor_diesel\"><\/span>Motor diesel<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El motor di\u00e9sel o a gasoil en cambio, produce la energ\u00eda mec\u00e1nica que necesita a trav\u00e9s de la transformaci\u00f3n de calor, por lo que se le conoce como motor t\u00e9rmico. El combustible arde dentro de una c\u00e1mara de combusti\u00f3n transformando la energ\u00eda qu\u00edmica en energ\u00eda mec\u00e1nica, capaz de mover un pist\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Diferencias_entre_un_motor_diesel_y_uno_de_gasolina\"><\/span>Diferencias entre un motor diesel y uno de gasolina<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La <strong>relaci\u00f3n de compresi\u00f3n<\/strong> de ambos motores difiere enormemente. En los motores di\u00e9sel es mucho mayor, ya que necesitan que el aire comprimido alcance una mayor temperatura para que el combustible encienda.<\/p>\n<p>Esta mayor compresi\u00f3n obliga a que las partes del motor di\u00e9sel deban tener una mayor resistencia que las del motor a gasolina, debido a que deben soportar mayor presi\u00f3n.<\/p>\n<p>Las <strong>buj\u00edas<\/strong> en el motor de gasolina se usan para producir la chispa en la fase de compresi\u00f3n para iniciar la combusti\u00f3n, mientras que en los motores di\u00e9sel, se utilizan para ayudar a calentar el aire en procesos de arranque en fr\u00edo.<\/p>\n<p>En general, un <strong>motor di\u00e9sel requiere de menos<\/strong> <strong>reparaciones<\/strong>, aunque \u00e9stas pueden llegar a tener un mayor coste respecto a las reparaciones de un motor a gasolina. Otro factor que puede exigirle m\u00e1s a tu bolsillo es <strong>la bater\u00eda<\/strong>; los coches de gasolina requieren menos energ\u00eda el\u00e9ctrica para arrancar. En cambio, en los coches di\u00e9sel, la pueden desgastar m\u00e1s r\u00e1pido.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Motor de gasolina, motor di\u00e9sel, tal vez sea una cuesti\u00f3n que parezca algo pasado de moda o fuera de contexto. Sin embargo, son los tipos de motor que m\u00e1s se utilizan en la actualidad y cada uno tiene sus propias caracter\u00edsticas que lo diferencian del otro. A continuaci\u00f3n, daremos un repaso sobre \u00e9stas caracter\u00edsticas relevantes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":815,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[131],"tags":[],"class_list":["post-816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfEn qu\u00e9 se diferencia un motor de gasolina de uno di\u00e9sel?<\/title>\n<meta name=\"description\" content=\"Motor de gasolina, motor di\u00e9sel, tal vez sea una cuesti\u00f3n que parezca algo pasado de moda o fuera de contexto. Sin embargo, son los tipos de motor que m\u00e1s se utilizan en la actualidad y cada uno tiene sus propias caracter\u00edsticas que lo diferencian del otro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEn qu\u00e9 se diferencia un motor de gasolina de uno di\u00e9sel?\" \/>\n<meta property=\"og:description\" content=\"Motor de gasolina, motor di\u00e9sel, tal vez sea una cuesti\u00f3n que parezca algo pasado de moda o fuera de contexto. Sin embargo, son los tipos de motor que m\u00e1s se utilizan en la actualidad y cada uno tiene sus propias caracter\u00edsticas que lo diferencian del otro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/\" \/>\n<meta property=\"og:site_name\" content=\"Estaci\u00f3 de Servei Maset\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-13T12:14:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/estaciodeserveimaset.com\/wp-content\/uploads\/2018\/04\/motor_gasolina_diesel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"737\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Estaci\u00f3 de Servei Maset\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Estaci\u00f3 de Servei Maset\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/\"},\"author\":{\"name\":\"Estaci\u00f3 de Servei Maset\",\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/#\\\/schema\\\/person\\\/06754f41b30c7200ac8cc1a27a51a606\"},\"headline\":\"\u00bfEn qu\u00e9 se diferencia un motor de gasolina de uno di\u00e9sel?\",\"datePublished\":\"2018-04-13T12:14:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/\"},\"wordCount\":397,\"image\":{\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/motor_gasolina_diesel.jpg\",\"articleSection\":[\"Consejos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/\",\"url\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/\",\"name\":\"\u00bfEn qu\u00e9 se diferencia un motor de gasolina de uno di\u00e9sel?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/motor_gasolina_diesel.jpg\",\"datePublished\":\"2018-04-13T12:14:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/#\\\/schema\\\/person\\\/06754f41b30c7200ac8cc1a27a51a606\"},\"description\":\"Motor de gasolina, motor di\u00e9sel, tal vez sea una cuesti\u00f3n que parezca algo pasado de moda o fuera de contexto. Sin embargo, son los tipos de motor que m\u00e1s se utilizan en la actualidad y cada uno tiene sus propias caracter\u00edsticas que lo diferencian del otro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/motor_gasolina_diesel.jpg\",\"contentUrl\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/motor_gasolina_diesel.jpg\",\"width\":\"1024\",\"height\":\"737\",\"caption\":\"motor de gasolina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/motor-gasolina-diesel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEn qu\u00e9 se diferencia un motor de gasolina de uno di\u00e9sel?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/#website\",\"url\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/\",\"name\":\"Estaci\u00f3 de Servei Maset\",\"description\":\"Gasolina i gasoil de calefacci\u00f3 a domicili\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/estaciodeserveimaset.com\\\/#\\\/schema\\\/person\\\/06754f41b30c7200ac8cc1a27a51a606\",\"name\":\"Estaci\u00f3 de Servei Maset\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7fb4cff0b30bb664a3fe8271f60c493235311eb1bb917d43fd79a61ae8e99f8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7fb4cff0b30bb664a3fe8271f60c493235311eb1bb917d43fd79a61ae8e99f8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7fb4cff0b30bb664a3fe8271f60c493235311eb1bb917d43fd79a61ae8e99f8?s=96&d=mm&r=g\",\"caption\":\"Estaci\u00f3 de Servei Maset\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEn qu\u00e9 se diferencia un motor de gasolina de uno di\u00e9sel?","description":"Motor de gasolina, motor di\u00e9sel, tal vez sea una cuesti\u00f3n que parezca algo pasado de moda o fuera de contexto. Sin embargo, son los tipos de motor que m\u00e1s se utilizan en la actualidad y cada uno tiene sus propias caracter\u00edsticas que lo diferencian del otro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfEn qu\u00e9 se diferencia un motor de gasolina de uno di\u00e9sel?","og_description":"Motor de gasolina, motor di\u00e9sel, tal vez sea una cuesti\u00f3n que parezca algo pasado de moda o fuera de contexto. Sin embargo, son los tipos de motor que m\u00e1s se utilizan en la actualidad y cada uno tiene sus propias caracter\u00edsticas que lo diferencian del otro.","og_url":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/","og_site_name":"Estaci\u00f3 de Servei Maset","article_published_time":"2018-04-13T12:14:19+00:00","og_image":[{"width":1024,"height":737,"url":"https:\/\/estaciodeserveimaset.com\/wp-content\/uploads\/2018\/04\/motor_gasolina_diesel.jpg","type":"image\/jpeg"}],"author":"Estaci\u00f3 de Servei Maset","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Estaci\u00f3 de Servei Maset","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/#article","isPartOf":{"@id":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/"},"author":{"name":"Estaci\u00f3 de Servei Maset","@id":"https:\/\/estaciodeserveimaset.com\/#\/schema\/person\/06754f41b30c7200ac8cc1a27a51a606"},"headline":"\u00bfEn qu\u00e9 se diferencia un motor de gasolina de uno di\u00e9sel?","datePublished":"2018-04-13T12:14:19+00:00","mainEntityOfPage":{"@id":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/"},"wordCount":397,"image":{"@id":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/#primaryimage"},"thumbnailUrl":"https:\/\/estaciodeserveimaset.com\/wp-content\/uploads\/2018\/04\/motor_gasolina_diesel.jpg","articleSection":["Consejos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/","url":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/","name":"\u00bfEn qu\u00e9 se diferencia un motor de gasolina de uno di\u00e9sel?","isPartOf":{"@id":"https:\/\/estaciodeserveimaset.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/#primaryimage"},"image":{"@id":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/#primaryimage"},"thumbnailUrl":"https:\/\/estaciodeserveimaset.com\/wp-content\/uploads\/2018\/04\/motor_gasolina_diesel.jpg","datePublished":"2018-04-13T12:14:19+00:00","author":{"@id":"https:\/\/estaciodeserveimaset.com\/#\/schema\/person\/06754f41b30c7200ac8cc1a27a51a606"},"description":"Motor de gasolina, motor di\u00e9sel, tal vez sea una cuesti\u00f3n que parezca algo pasado de moda o fuera de contexto. Sin embargo, son los tipos de motor que m\u00e1s se utilizan en la actualidad y cada uno tiene sus propias caracter\u00edsticas que lo diferencian del otro.","breadcrumb":{"@id":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/#primaryimage","url":"https:\/\/estaciodeserveimaset.com\/wp-content\/uploads\/2018\/04\/motor_gasolina_diesel.jpg","contentUrl":"https:\/\/estaciodeserveimaset.com\/wp-content\/uploads\/2018\/04\/motor_gasolina_diesel.jpg","width":"1024","height":"737","caption":"motor de gasolina"},{"@type":"BreadcrumbList","@id":"https:\/\/estaciodeserveimaset.com\/es\/motor-gasolina-diesel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/estaciodeserveimaset.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfEn qu\u00e9 se diferencia un motor de gasolina de uno di\u00e9sel?"}]},{"@type":"WebSite","@id":"https:\/\/estaciodeserveimaset.com\/#website","url":"https:\/\/estaciodeserveimaset.com\/","name":"Estaci\u00f3 de Servei Maset","description":"Gasolina i gasoil de calefacci\u00f3 a domicili","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/estaciodeserveimaset.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/estaciodeserveimaset.com\/#\/schema\/person\/06754f41b30c7200ac8cc1a27a51a606","name":"Estaci\u00f3 de Servei Maset","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b7fb4cff0b30bb664a3fe8271f60c493235311eb1bb917d43fd79a61ae8e99f8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b7fb4cff0b30bb664a3fe8271f60c493235311eb1bb917d43fd79a61ae8e99f8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b7fb4cff0b30bb664a3fe8271f60c493235311eb1bb917d43fd79a61ae8e99f8?s=96&d=mm&r=g","caption":"Estaci\u00f3 de Servei Maset"}}]}},"_links":{"self":[{"href":"https:\/\/estaciodeserveimaset.com\/es\/wp-json\/wp\/v2\/posts\/816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/estaciodeserveimaset.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/estaciodeserveimaset.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/estaciodeserveimaset.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/estaciodeserveimaset.com\/es\/wp-json\/wp\/v2\/comments?post=816"}],"version-history":[{"count":0,"href":"https:\/\/estaciodeserveimaset.com\/es\/wp-json\/wp\/v2\/posts\/816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/estaciodeserveimaset.com\/es\/wp-json\/wp\/v2\/media\/815"}],"wp:attachment":[{"href":"https:\/\/estaciodeserveimaset.com\/es\/wp-json\/wp\/v2\/media?parent=816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/estaciodeserveimaset.com\/es\/wp-json\/wp\/v2\/categories?post=816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/estaciodeserveimaset.com\/es\/wp-json\/wp\/v2\/tags?post=816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}